{"id":10534,"date":"2011-10-13T18:35:40","date_gmt":"2011-10-13T16:35:40","guid":{"rendered":"http:\/\/blog-corbeil-essonnes.fr\/WordPress3\/?p=10534"},"modified":"2011-10-18T17:30:30","modified_gmt":"2011-10-18T15:30:30","slug":"assemblee-citoyenne-du-front-de-gauche","status":"publish","type":"post","link":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/2011\/10\/13\/assemblee-citoyenne-du-front-de-gauche\/","title":{"rendered":"Assembl\u00e9e Citoyenne du Front de Gauche"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"center\"><a href=\"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/2011\/10\/13\/assemblee-citoyenne-du-front-de-gauche\/image2\/\" rel=\"attachment wp-att-10536\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-10536\" title=\"Image2\" src=\"https:\/\/i0.wp.com\/blog-corbeil-essonnes.fr\/WordPress3\/wp-content\/uploads\/2011\/10\/Image2-300x284.jpg?resize=300%2C284&#038;ssl=1\" alt=\"\" width=\"300\" height=\"284\" data-recalc-dims=\"1\" \/><\/a>Le monde conna\u00eet une crise \u00e9conomique et politique sans pr\u00e9c\u00e9dent depuis des d\u00e9cennies. L&rsquo;impasse des politiques n\u00e9o-lib\u00e9rales qui concentrent l&rsquo;argent et le pouvoir dans les mains d&rsquo;une poign\u00e9e d&rsquo;oligarques nous poussent \u00e0 r\u00e9agir.<!--more--><\/p>\n<p>NOUS NE VOULONS PAS DE CE MONDE LA !<\/p>\n<p>Imposons d\u00e8s aujourd&rsquo;hui une autre logique :<\/p>\n<p>\u25ba une VIe R\u00e9publique<br \/>\n\u25ba un salaire et un revenu maximum<br \/>\n\u25ba de vrais services publics<br \/>\n\u25ba une planification \u00e9cologique<br \/>\n\u25ba la sortie du trait\u00e9 de Lisbonne<\/p>\n<p>Utilisez le Front de Gauche pour mettre un coup de pied dans la fourmili\u00e8re et renverser ce syst\u00e8me\u00a0 dirig\u00e9 par la finance.<\/p>\n<h1 align=\"center\"><strong>Assembl\u00e9e Citoyenne<\/strong><\/h1>\n<h1 align=\"center\"><strong>Lundi 17 octobre,<\/strong><\/h1>\n<h1 align=\"center\"><strong>\u00a020h00<\/strong><\/h1>\n<h1 align=\"center\"><strong>\u00e0 la F\u00e9d\u00e9ration du PCF 91<\/strong><\/h1>\n<h1 align=\"center\"><strong>Impasse Delcourt, <\/strong><\/h1>\n<h1 align=\"center\"><strong>69 rue d&rsquo;Angoul\u00e8me \u00e0 Corbeil-Essonnes<\/strong><br \/>\n<strong>\u00a0<\/strong><\/h1>\n<p align=\"center\">\n","protected":false},"excerpt":{"rendered":"<p>Le monde conna\u00eet une crise \u00e9conomique et politique sans pr\u00e9c\u00e9dent depuis des d\u00e9cennies. L&rsquo;impasse des politiques n\u00e9o-lib\u00e9rales qui concentrent l&rsquo;argent et le pouvoir dans les &hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[4312,4330,4329],"tags":[4418,4396,4760],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/10534"}],"collection":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/comments?post=10534"}],"version-history":[{"count":0,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/10534\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/media?parent=10534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/categories?post=10534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/tags?post=10534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}