{"id":4325,"date":"2007-09-11T13:35:44","date_gmt":"2007-09-11T13:35:44","guid":{"rendered":"http:\/\/corbeilessonnes.unblog.fr\/2007\/09\/11\/foire-de-corbeil-essonnes-des-portugais-insatisfaits\/"},"modified":"2014-10-26T18:39:30","modified_gmt":"2014-10-26T17:39:30","slug":"foire-de-corbeil-essonnes-des-portugais-insatisfaits","status":"publish","type":"post","link":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/2007\/09\/11\/foire-de-corbeil-essonnes-des-portugais-insatisfaits\/","title":{"rendered":"Foire de Corbeil-essonnes des Portugais insatisfaits"},"content":{"rendered":"<p>La Foire de Corbeil-Essonnes se termine et nous saluons les associations de portugais qui ont essay\u00e9 d&rsquo;animer avec leurs moyens l&rsquo;espace qui leur avait \u00e9t\u00e9 attribu\u00e9.<\/p>\n<p>Aujourd&rsquo;hui ils expriment leur d\u00e9ception de ne pas avoir pu donner une image plus large de leur pays, il est vrai que comme les autres ann\u00e9es les invit\u00e9s n&rsquo;ont pas \u00e9t\u00e9 gat\u00e9s.<\/p>\n<p>Le Portugal c&rsquo;est bien sur un folklore riche ,color\u00e9, vivant mais c&rsquo;est aussi une histoire , des \u00e9crivains des peintres et beaucoup d&rsquo;autres richesses. Nous aurions aim\u00e9 d\u00e9couvrir tout cela et restons sur notre faim.<\/p>\n<p>Ce n&rsquo;est pas la premi\u00e8re fois que l&rsquo;invit\u00e9 est vu de fa\u00e7on r\u00e9ductrice voir pour certaines ann\u00e9es caricaturales.<\/p>\n<p>En effet que penser de la repr\u00e9sentation du Br\u00e9sil sous l&rsquo;angle uniquement du carnaval de Rio, du P\u00e9rou dont l&rsquo;histoire est si riche repr\u00e9senter par un lama affubl\u00e9 d&rsquo;un bonnet.<\/p>\n<p>Les celtes l&rsquo;ann\u00e9e derni\u00e8re furent mieux loti ,pourtant ,pour eux aussi beaucoup de choses \u00e9taient absentes et voir une affiche o\u00f9 l&rsquo;on trouve une cornemuse et un \u00e9cossais en kilt est l\u00e0 aussi tr\u00e8s caricaturale.<\/p>\n<p>Si le concept d&rsquo;invit\u00e9 d&rsquo;honneur devait perdurer ,il serait souhaitable de se donner r\u00e9ellement les moyens de mettre en valeur ces invit\u00e9s et de leur permettre de partager avec nous les beaut\u00e9s et les int\u00e9r\u00eats multiples de leur pays ou culture.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Foire de Corbeil-Essonnes se termine et nous saluons les associations de portugais qui ont essay\u00e9 d&rsquo;animer avec leurs moyens l&rsquo;espace qui leur avait \u00e9t\u00e9 &hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[4311,1,4328],"tags":[4456,4497],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/4325"}],"collection":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/comments?post=4325"}],"version-history":[{"count":0,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/4325\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/media?parent=4325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/categories?post=4325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/tags?post=4325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}