{"id":4355,"date":"2007-10-17T11:21:41","date_gmt":"2007-10-17T11:21:41","guid":{"rendered":"http:\/\/corbeilessonnes.unblog.fr\/2007\/10\/17\/incendie-aux-tarterets\/"},"modified":"2014-10-27T09:41:49","modified_gmt":"2014-10-27T08:41:49","slug":"incendie-aux-tarterets","status":"publish","type":"post","link":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/2007\/10\/17\/incendie-aux-tarterets\/","title":{"rendered":"Incendie aux Tarter\u00eats"},"content":{"rendered":"<p>En fin de matin\u00e9e un incendie s&rsquo;est d\u00e9clar\u00e9 dans une tour de la cit\u00e9 Tarter\u00eats, il n&rsquo;y a pas eu de bless\u00e9 grave.<\/p>\n<p>Les informations en ma possession font \u00e9tat de 20 personnes intoxiqu\u00e9es , les plus touch\u00e9es ont \u00e9t\u00e9 dirig\u00e9es vers les h\u00f4pitaux environnants. Les familles ont \u00e9t\u00e9 regroup\u00e9es dans le gymnase face \u00e0 la mosqu\u00e9e.<\/p>\n<p>Le b\u00e2timent semble condamn\u00e9. Le feu a pris au troisi\u00e8me \u00e9tage et s&rsquo;est propag\u00e9 jusqu&rsquo;au 12\u00e9me .<\/p>\n<p>Quarante huit familles sont \u00e0 reloger. Nous esp\u00e9rons que le bailleur pourra satisfaire les demandes des locataires. Une r\u00e9union a eu lieu \u00e0 16h dans le local de l&rsquo;association le lien citoyens.<\/p>\n<p>Bruno Piriou conseiller g\u00e9n\u00e9ral du canton s&rsquo;est adress\u00e9 aux habitants pour lancer un appel \u00e0 la solidarit\u00e9: son courrier :incendietarterets<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En fin de matin\u00e9e un incendie s&rsquo;est d\u00e9clar\u00e9 dans une tour de la cit\u00e9 Tarter\u00eats, il n&rsquo;y a pas eu de bless\u00e9 grave. Les informations &hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[4311,1,4328],"tags":[4757,4361],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/4355"}],"collection":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/comments?post=4355"}],"version-history":[{"count":0,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/4355\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/media?parent=4355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/categories?post=4355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/tags?post=4355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}