{"id":4997,"date":"2009-10-19T14:28:58","date_gmt":"2009-10-19T14:28:58","guid":{"rendered":"http:\/\/corbeilessonnes.unblog.fr\/2009\/10\/19\/intervention-de-martine-billard-a-lassemblee-nationale-contre-le-redecoupage-electoral\/"},"modified":"2014-09-29T18:31:04","modified_gmt":"2014-09-29T17:31:04","slug":"intervention-de-martine-billard-a-lassemblee-nationale-contre-le-redecoupage-electoral","status":"publish","type":"post","link":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/2009\/10\/19\/intervention-de-martine-billard-a-lassemblee-nationale-contre-le-redecoupage-electoral\/","title":{"rendered":"Intervention de Martine Billard  \u00e0 l\u2019Assembl\u00e9e nationale contre le red\u00e9coupage \u00e9lectoral"},"content":{"rendered":"<div>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><span style=\"text-decoration: underline;\"><strong>Assembl\u00e9e Nationale, le mercredi 14 octobre 2009<\/strong><\/span>.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>M. le pr\u00e9sident.<\/strong> La parole est \u00e0 Mme Martine Billard.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Mme Martine Billard.<\/strong> Monsieur le pr\u00e9sident, monsieur le secr\u00e9taire d&rsquo;\u00c9tat, monsieur le rapporteur, le red\u00e9coupage \u00e9tait obligatoire, c&rsquo;est ind\u00e9niable. Toutefois, on peut imaginer que, lorsqu&rsquo;il s&rsquo;agit de red\u00e9finir les r\u00e8gles de l&rsquo;\u00e9lection des repr\u00e9sentants du peuple, on le fasse au nom du respect, \u00e0 la fois, de la d\u00e9mocratie, de la pluralit\u00e9 politique du pays et de l&rsquo;\u00e9quilibre politique des forces qui participent au jeu d\u00e9mocratique. Or le moins qu&rsquo;on puisse dire est que le r\u00e9sultat qui nous est propos\u00e9 est bien loin de respecter ces r\u00e8gles, alors m\u00eame que le scrutin uninominal pr\u00e9sente d\u00e9j\u00e0 par lui-m\u00eame de nombreux inconv\u00e9nients, que plusieurs orateurs ont \u00e9voqu\u00e9s avant moi.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">En effet, ce type de scrutin, non content de d\u00e9former la repr\u00e9sentation politique du pays, favorise les notables lorsque s&rsquo;y ajoute le cumul des mandats, \u00e0 savoir les hommes de plus de cinquante ans appartenant aux cat\u00e9gories sociales sup\u00e9rieures.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><!--more--><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">La repr\u00e9sentation politique n&rsquo;est donc pas \u00e0 l&rsquo;image du pays : c&rsquo;est flagrant notamment en ce qui concerne les femmes, puisque seulement 18,5 % de femmes si\u00e8gent \u00e0 l&rsquo;Assembl\u00e9e nationale. Le fait qu&rsquo;il s&rsquo;agisse d&rsquo;un record depuis la Lib\u00e9ration ne fait que confirmer que l&rsquo;\u00e9volution est tr\u00e8s lente et que de nombreuses d\u00e9cennies seront encore n\u00e9cessaires pour atteindre, un jour, la parit\u00e9. Dois-je rappeler que la France est l&rsquo;un des derniers pays de l&rsquo;Union europ\u00e9enne en mati\u00e8re de repr\u00e9sentation des femmes ?<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Monsieur le secr\u00e9taire d&rsquo;\u00c9tat, vous avez argu\u00e9 que les femmes avaient le droit de se pr\u00e9senter partout : c&rsquo;est encore heureux ! Il serait inou\u00ef que les textes pr\u00e9voient le contraire. Je vous rappelle toutefois que votre parti, l&rsquo;UMP, a d\u00fb payer une amende de 4 millions d&rsquo;euros en 2007 du fait qu&rsquo;il n&rsquo;avait pas pr\u00e9sent\u00e9 un nombre suffisant de femmes : 153 pour 435 hommes.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Je le r\u00e9p\u00e8te : le scrutin uninominal d\u00e9forme la repr\u00e9sentation du peuple fran\u00e7ais, ce qui n&rsquo;est pas sans cons\u00e9quence sur la d\u00e9mocratie. Faut-il rappeler que, lors de la r\u00e9vision constitutionnelle, loin de modifier ce mode de scrutin, vous avez refus\u00e9 l&rsquo;instauration du scrutin proportionnel, lequel est pratiqu\u00e9 dans quasiment tous les pays, \u00e0 l&rsquo;exception de la France et de la Grande-Bretagne ? Je laisse donc de c\u00f4t\u00e9 le d\u00e9bat portant sur la dose de proportionnelle ou sur la pr\u00e9sence ou non d&rsquo;un seuil puisque, de toute fa\u00e7on, nous en restons au syst\u00e8me des circonscriptions.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Monsieur le rapporteur, vous avez affirm\u00e9 hier que le red\u00e9coupage repose sur des crit\u00e8res d\u00e9mographiques, strictement d\u00e9mographiques. M. Ciotti, s&rsquo;exprimant au nom de l&rsquo;UMP sur ce texte, a \u00e9voqu\u00e9, de son c\u00f4t\u00e9, les crit\u00e8res d&rsquo;objectivit\u00e9 du texte et le fait que le secr\u00e9taire d&rsquo;\u00c9tat a fait preuve de sinc\u00e9rit\u00e9 dans son red\u00e9coupage. Permettez-moi, monsieur le secr\u00e9taire d&rsquo;\u00c9tat, de me montrer quelque peu d\u00e9sagr\u00e9able, au travers d&rsquo;un exemple qui est en compl\u00e8te contradiction avec de telles affirmations : non, vous n&rsquo;avez pas \u00e9t\u00e9 sinc\u00e8re ; non, le texte ne repose pas sur des crit\u00e8res d\u00e9mographiques objectifs !<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">On aurait pu, en effet, raisonnablement penser que, comme Paris n&rsquo;est pas pourvu de cantons, c&rsquo;est sur des bases d\u00e9mographiques que s&rsquo;y op\u00e9rerait un red\u00e9coupage qui entra\u00eene la disparition de trois circonscriptions. Or un \u00e9lu de l&rsquo;UMP, maire du premier arrondissement de Paris et candidat malheureux aux \u00e9lections l\u00e9gislatives de 2002 et de 2007, a expliqu\u00e9, en avril dernier, la fa\u00e7on dont, \u00e0 ses yeux, le red\u00e9coupage \u00e0 Paris devait \u00eatre pens\u00e9 ; ses propos ont \u00e9t\u00e9 repris dans une d\u00e9p\u00eache de l&rsquo;AFP. Selon lui, \u00ab la premi\u00e8re circonscription de Paris \u00bb, qui regroupe les quatre premiers arrondissements, \u00ab exploserait. Dans son contour actuel elle est irr\u00e9cup\u00e9rable pour la droite \u00bb. Monsieur le secr\u00e9taire d&rsquo;\u00c9tat, le fait qu&rsquo;une circonscription soit irr\u00e9cup\u00e9rable pour la droite entre-t-il dans les crit\u00e8res d\u00e9mographiques reposant sur des principes d&rsquo;objectivit\u00e9 et de sinc\u00e9rit\u00e9 ? Dix circonscriptions \u00e9taient plus petites que la premi\u00e8re circonscription de Paris. Du reste, le probl\u00e8me n&rsquo;est pas la premi\u00e8re circonscription de Paris, mais la conception qui pr\u00e9side au red\u00e9coupage de Paris.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Le fait qu&rsquo;un responsable de l&rsquo;UMP explique qu&rsquo;une circonscription doit dispara\u00eetre parce que l&rsquo;UMP ne peut pas la reprendre r\u00e9v\u00e8le la fa\u00e7on dont ce red\u00e9coupage a \u00e9t\u00e9 globalement pens\u00e9. C&rsquo;est pourquoi je regrette que la commission Gu\u00e9na n&rsquo;ait pas accept\u00e9 de recevoir les repr\u00e9sentants des forces politiques, parce qu&rsquo;il aurait \u00e9t\u00e9 int\u00e9ressant de lui expliquer sur quel principe reposait ce red\u00e9coupage. Quelle n&rsquo;aurait pas \u00e9t\u00e9 sa surprise !<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">M. Fran\u00e7ois Asensi a cit\u00e9 des red\u00e9coupages de circonscriptions qui suivent les voies ferr\u00e9es. Il faut esp\u00e9rer que la SNCF n&rsquo;en ferme pas d&rsquo;ici l\u00e0, car le red\u00e9coupage perdrait en compr\u00e9hension. \u00c0 Paris, le red\u00e9coupage suit les rues et il faut savoir qu il reposait auparavant sur le principe h\u00e9lico\u00efdal de l&rsquo;escargot. Un tel principe avait sa coh\u00e9rence. Malheureusement, c&rsquo;est le n&rsquo;importe quoi qui pr\u00e9side au prochain red\u00e9coupage, puisque celui-ci ne r\u00e9v\u00e8le, d&rsquo;un bout \u00e0 l&rsquo;autre de la capitale, aucune continuit\u00e9. D\u00e9sormais, trois circonscriptions couvriront trois \u00e0 quatre arrondissements alors que c&rsquo;\u00e9tait auparavant le cas d&rsquo;une seule en raison de la faiblesse d\u00e9mographique des arrondissements concern\u00e9s.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Monsieur le secr\u00e9taire d&rsquo;\u00c9tat, \u00e0 l&rsquo;instar d&rsquo;un grand nombre de d\u00e9put\u00e9s de l&rsquo;UMP, et de quelques-uns de gauche, vous justifiez le cumul des mandats en invoquant la n\u00e9cessit\u00e9 de l&rsquo;ancrage territorial pour faire un bon d\u00e9put\u00e9. Il ne doit donc y avoir que de mauvais d\u00e9put\u00e9s dans les pays \u00e9trangers, o\u00f9 on ne pratique pas le cumul comme en France ! Je pense que lorsqu&rsquo;on se pr\u00e9sente devant des \u00e9lecteurs, la moindre des choses, une fois \u00e9lue, c&rsquo;est d&rsquo;accomplir le mieux possible son mandat, donc d&rsquo;y consacrer tout son temps. Nous sommes du reste correctement r\u00e9mun\u00e9r\u00e9s \u00e0 cette fin.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Monsieur le secr\u00e9taire d&rsquo;\u00c9tat, si l&rsquo;implantation territoriale est n\u00e9cessaire, les circonscriptions doivent avoir une continuit\u00e9 territoriale correspondant \u00e0 un minimum de coh\u00e9rence. Or tel n&rsquo;est pas le cas puisque le red\u00e9coupage que vous effectuez dans de nombreux d\u00e9partements comme \u00e0 Paris est de moins en moins coh\u00e9rent sur le plan territorial. Vous ne pouvez donc pas, \u00e0 la fois, justifier le cumul par la n\u00e9cessit\u00e9 de l&rsquo;ancrage territorial et casser, dans de nombreux cas, ce m\u00eame ancrage.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Je le r\u00e9p\u00e8te : si, comme vous l&rsquo;avez affirm\u00e9 dans cet h\u00e9micycle, nous sommes les d\u00e9put\u00e9s de la nation et si notre mission est de d\u00e9fendre l&rsquo;int\u00e9r\u00eat g\u00e9n\u00e9ral &#8211; c&rsquo;est effectivement ce que je pense et je suis pr\u00eate \u00e0 vous rejoindre sur ce point -, alors, peu importe la circonscription et nous ne devons pas accepter le cumul.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Surtout, monsieur le secr\u00e9taire d&rsquo;\u00c9tat, vous ne pouvez pas, \u00e0 la fois, soutenir que nous sommes les d\u00e9put\u00e9s de la nation et vous opposer au scrutin proportionnel. En effet, les d\u00e9put\u00e9s de la nation doivent repr\u00e9senter la pluralit\u00e9 politique du pays, ce qu&rsquo;interdisent de faire le mode de scrutin uninominal, le cumul des mandats et, d\u00e9sormais, votre red\u00e9coupage, qui renforcera le bipartisme, comme le renforcera \u00e9galement la modification du mode de scrutin \u00e0 laquelle vous proc\u00e9derez pour les \u00e9lections territoriales.<\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Telles sont, monsieur le secr\u00e9taire d&rsquo;\u00c9tat, les critiques que je tenais \u00e0 formuler \u00e0 propos de votre mod\u00e8le de red\u00e9coupage, qui ne respecte pas le mod\u00e8le r\u00e9publicain, ce que nous regrettons. (Applaudissements sur les bancs des groupes GDR et SRC.)<\/span><\/p>\n<p><span style=\"font-family: Arial;\">texte publi\u00e9 sur le site du\u00a0<a href=\"http:\/\/www.lepartidegauche.fr\/\">parti de gauche<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"text-decoration: underline;\"><br \/>\n<\/span><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assembl\u00e9e Nationale, le mercredi 14 octobre 2009. M. le pr\u00e9sident. La parole est \u00e0 Mme Martine Billard. Mme Martine Billard. Monsieur le pr\u00e9sident, monsieur le &hellip; <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[4318,1,4319],"tags":[4758,4483],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/4997"}],"collection":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/comments?post=4997"}],"version-history":[{"count":0,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/posts\/4997\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/media?parent=4997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/categories?post=4997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-corbeil-essonnes.fr\/WordPress3\/wp-json\/wp\/v2\/tags?post=4997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}